{"id":56,"date":"2019-03-01T09:23:06","date_gmt":"2019-03-01T09:23:06","guid":{"rendered":"http:\/\/qcandles.wwwnl1-lr4.supercp.com\/?page_id=56"},"modified":"2022-11-23T05:11:41","modified_gmt":"2022-11-23T13:11:41","slug":"site-map","status":"publish","type":"page","link":"https:\/\/qcandles.com\/development\/site-map\/","title":{"rendered":"Site Map"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1 class=\"custom_heading_title_section\">Site Map<\/h1>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"left\">\n<ul>\n<li><a href=\"\/led-flameless-candles\/\">LED Flameless Candles<\/a>\n<ul>\n<li><a href=\"\/product-category\/led-flameless-candles\/round-flameless-candles\/\">Round Flameless Candles <\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/square-flameless-candles\/\">Square Flameless Candles <\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/rectangle-flameless-candles\/\">Rectangle Flameless Candles <\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/other-shapes\/\">Other Shapes Flameless Candles<\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/oriental-design-flameless-candles\/\">Oriental Design Flameless Candles <\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/personalized-flameless-candles\/\">Personalized Flameless Candles <\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/rechargeable-candles-commercial-grade\/\">Rechargeable Candles \/ Commercial Grade<\/a>\n<ul>\n<li><a href=\"\/product-category\/led-flameless-candles\/rechargeable-candles-commercial-grade\/the-most-advanced-commercial-grade-candle-systems-in-outdoor-up-to-36k-hours-lifespan-wax-holders-not-included\/\">The Most Advanced Commercial Grade Candle Systems &#8211; In\/Outdoor up to 36K Hours Lifespan (Wax Holders not included)<\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/rechargeable-candles-commercial-grade\/the-most-advanced-commercial-grade-candle-system-up-to-36k-hours-lifespan-in-outdoor-wax-holders-included\/\">The Most Advanced Commercial Grade Candle System, up to 36K Hours Lifespan, In\/Outdoor (Wax Holders Included)<\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/rechargeable-candles-commercial-grade\/commercial-grade-10500-hour-lifespan-sets-of-12-to-48-wax-holders-included\/\">Commercial Grade 10500 Hour Lifespan (Sets of 12 to 48) Wax Holders Included<\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/rechargeable-candles-commercial-grade\/rechargeable-candles-parts\/\">Rechargeable Candles &#8211; PARTS <\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/floating-flameless-led-candles\/\">Floating Flameless LED Candles<\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/outdoor-flameless-candles\/\">Outdoor Flameless Candles <\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/led-lights-accessories\/\">LED Lights &amp; Accessories <\/a><\/li>\n<li><a href=\"\/product-category\/led-flameless-candles\/colors\/\">Colors <\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"\/candle-holders\/\">Candle Holders<\/a>\n<ul>\n<li><a href=\"\/product-category\/candle-holders\/personalized-candle-holders\/\">Personalized Candle Holders<\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/horizontal-design-candle-holders\/\">Horizontal Design Candle Holders <\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/extra-large-candle-holders-stands\/\"> Extra Large Candle Holders &amp; Stands<\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/hurricane-design-candle-holders\/\">Hurricane Design Candle Holders<\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/vineyard-design-candle-holders\/\"> Vineyard Design Candle Holders<\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/mix-designs-candle-holders\/\">Mix Designs Candle Holders<\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/glass-candle-holders\/\">Glass Candle Holders <\/a>\n<ul>\n<li><a href=\"\/product-category\/candle-holders\/glass-candle-holders\/glass-candle-holders-small-size\/\">Glass Candle Holders &#8211; Small Size<\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/glass-candle-holders\/glass-candle-holders-midsize\/\">Glass Candle Holders &#8211; Midsize<\/a><\/li>\n<li><a href=\"\/product-category\/candle-holders\/glass-candle-holders\/glass-candle-holders-large-size\/\">Glass Candle Holders &#8211; Large Size<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li><a href=\"\/wax-luminaries\/\">Wax Luminaries<\/a>\n<ul>\n<li><a href=\"\/product-category\/wax-luminaries\/round-wax-luminaries\/\">Round Wax Luminaries<\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/square-wax-luminaries\/\">Square Wax Luminaries<\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/rectangle-wax-luminaries\/\">Rectangle Wax Luminaries <\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/other-shapes-wax-luminaries\/\">Other Shapes Wax Luminaries <\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/oriental-design-wax-luminaries\/\">Oriental Design Wax Luminaries <\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/personalized-wax-luminaries\/\">Personalized Wax Luminaries<\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/floating-reuseable-candles\/\">Floating Reuseable Candles <\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/liquid-wax-fuel-cells\/\">Liquid Wax Fuel Cells<\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/reuseable-candles-flame-on-top\/\">Reuseable Candles Flame on Top<\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/q-candles-collection\/\">Q Candles Collection<\/a><\/li>\n<li><a href=\"\/product-category\/wax-luminaries\/colors-wax-luminaries\/\">Colors<\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"\/hardwired-led-candle-systems\/\">Hardwired LED Candle Systems<\/a>\n<ul>\n<li><a href=\"https:\/\/qcandles.com\/product-category\/hardwired-led-candle-systems\/hardwired-led-candles\/\">Hardwired LED Candles<\/a><\/li>\n<li><a href=\"\/product-category\/hardwired-led-candle-systems\/hardwired-luminara-dancing-flame-led-candles-connect-up-to-96-candles-to-one-control\/\">Hardwired Luminara Dancing Flame LED Candles, (Connect up to 96 candles to one control) <\/a><\/li>\n<li><a href=\"\/product-category\/hardwired-led-candle-systems\/hardwired-electric-candle-systems-holders-included6-11-led-pack\/\">Hardwired Electric Candle Systems (Holders Included)(6-11 led pack)<\/a><\/li>\n<li><a href=\"\/product-category\/hardwired-led-candle-systems\/hardwired-electric-candle-systems-holders-included12-96-led-pack-up-to-96-candles-on-one-switch\/\">Hardwired Electric Candle Systems (Holders Included)(12-96 led pack (up to 96 candles on one switch)<\/a><\/li>\n<li><a href=\"\/product-category\/hardwired-led-candle-systems\/hardwired-led-candles-parts\/\">Hardwired Candle System &#8211; Expantion &#8211; PARTS <\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"\/pure-beeswax-candles\/\">Pure Beeswax Candles <\/a><\/li>\n<\/ul>\n<\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"right\">\n<ul>\n<li><a href=\"\/product-category\/special-offer\/\">Special Offers<\/a><\/li>\n<li><a href=\"\/my-account\/\">My Account<\/a>\n<ul>\n<li><a href=\"\/my-account\/\">Account Information<\/a><\/li>\n<li><a href=\"\/my-account\/edit-address\/\">Address Book<\/a><\/li>\n<li><a href=\"\/my-account\/orders\/\">Order History<\/a><\/li>\n<li><a href=\"\/my-account\/downloads\/\">Downloads<\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"\/cart\/\">Shopping Cart<\/a><\/li>\n<li><a href=\"\/checkout\/\">Checkout<\/a><\/li>\n<li>Information\n<ul>\n<li><a href=\"\/about-us\/\">About us<\/a><\/li>\n<li><a href=\"\/faq\/\">FAQ <\/a><\/li>\n<li><a href=\"\/wholesale-conditions\/\">Wholesale Terms &amp; Conditions<\/a><\/li>\n<li><a href=\"https:\/\/qcandles.com\/privacy\/\">Privacy Policy<\/a><\/li>\n<li><a href=\"\/terms-conditions\/\">Terms &amp; Conditions<\/a><\/li>\n<li><a href=\"\/contact-us\/\">Contact Us<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Site Map [\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text] LED Flameless Candles Round Flameless Candles Square Flameless Candles Rectangle Flameless Candles Other Shapes Flameless Candles Oriental Design Flameless Candles Personalized Flameless Candles Rechargeable Candles \/ Commercial Grade The Most Advanced Commercial Grade Candle Systems &#8211; In\/Outdoor up to 36K Hours Lifespan (Wax Holders not included) The Most Advanced Commercial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full-width.php","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/pages\/56"}],"collection":[{"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":20,"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/pages\/56\/revisions"}],"predecessor-version":[{"id":11678,"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/pages\/56\/revisions\/11678"}],"wp:attachment":[{"href":"https:\/\/qcandles.com\/development\/wp-json\/wp\/v2\/media?parent=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}